{"id":1023,"date":"2019-06-05T20:03:41","date_gmt":"2019-06-05T20:03:41","guid":{"rendered":"http:\/\/ficto.com.ec\/ficto\/?p=1023"},"modified":"2019-06-10T16:19:05","modified_gmt":"2019-06-10T16:19:05","slug":"que-es-una-textura-3d","status":"publish","type":"post","link":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/","title":{"rendered":"Que es una textura 3D"},"content":{"rendered":"<h4>Las texturas en 3D est\u00e1n en plena tendencia en el dise\u00f1o de espacios interiores, pues es un soluci\u00f3n pr\u00e1ctica e innovadora que genera m\u00faltiples posibilidades para un ambiente, combinan f\u00e1cilmente con el mobiliario y generan much\u00edsima personalidad al espacio. Con esta peque\u00f1a introducci\u00f3n, presentamos lo que desarrollamos para el espacio interior del Zeviche, un restaurante especializado en todo tipo de ceviches, como su nombre lo indica.<span class=\"Apple-converted-space\">\u00a0<\/span><\/h4>\n<figure id=\"attachment_1027\" aria-describedby=\"caption-attachment-1027\" style=\"width: 1280px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-1027\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/interior-zeviche.jpg?resize=640%2C427\" alt=\"Las texturas en 3D est\u00e1n en plena tendencia en el dise\u00f1o de espacios interiores, pues es un soluci\u00f3n pr\u00e1ctica e innovadora que genera m\u00faltiples posibilidades para un ambiente, combinan f\u00e1cilmente con el mobiliario y generan much\u00edsima personalidad al espacio. Con esta peque\u00f1a introducci\u00f3n, presentamos lo que desarrollamos para el espacio interior del Zeviche, un restaurante especializado en todo tipo de ceviches, como su nombre lo indica. Las texturas 3D generan mucha atenci\u00f3n y m\u00faltiples efectos, primero por sus diferentes lecturas de perspectiva y luego, al generar una trama de impacto visual, que hace que las paredes no requieran de ning\u00fan otro tipo de decoraci\u00f3n, como cuadros, espejos o estanter\u00edas. El Zeviche requer\u00eda de una textura que semeje las escamas de un pez, la materia prima de la mayor\u00eda de sus platos. Es as\u00ed que la esencia de la textura fue una placa con la forma de una escama con la que se desarroll\u00f3 todo un panel mas grande. En cada panel, cada placa est\u00e1 instalada con una inclinaci\u00f3n para dar la profundidad requerida y que se vaya conformando la textura general. El panel modular facilita la instalaci\u00f3n y poder contabilizar cuanta textura 3D hay por metro cuadrado. Este producto, ya se encuentra desarrollado y esquematizado para poder ser instalado en cualquier pared. Los colores y su paleta se pueden cambiar muy f\u00e1cilmente dependiendo de la personalidad que se le quiera dar al ambiente. As\u00ed mismo estamos en etapa de experimentaci\u00f3n para su ubicaci\u00f3n en diferentes tipos de mobiliario. Desde cajones de escritorios, hasta muebles de cocina. As\u00ed que cuando pienses en darle mas vida a un espacio o a tus objetos, piensa en crear una textura 3D. Tenemos otra experiencia de textura 3D en el espacio del restaurante el Zanto, que se puede ver en nuestra secci\u00f3n de portafolio.\" width=\"640\" height=\"427\" srcset=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/interior-zeviche.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/interior-zeviche.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/interior-zeviche.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/interior-zeviche.jpg?resize=1024%2C683&amp;ssl=1 1024w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-1027\" class=\"wp-caption-text\">Dise\u00f1o interior del restaurante Zeviche.\u00a0<\/figcaption><\/figure>\n<p>Las texturas 3D generan mucha atenci\u00f3n y m\u00faltiples efectos, primero por sus diferentes lecturas de perspectiva y luego, al generar una trama de impacto visual, que hace que las paredes no requieran de ning\u00fan otro tipo de decoraci\u00f3n, como cuadros, espejos o estanter\u00edas.<\/p>\n<p>El Zeviche requer\u00eda de una textura que semeje las escamas de un pez, la materia prima de la mayor\u00eda de sus platos. Es as\u00ed que la esencia de la textura fue una placa con la forma de una escama con la que se desarroll\u00f3 todo un panel mas grande. En cada panel, cada placa est\u00e1 instalada con una inclinaci\u00f3n para dar la profundidad requerida y que se vaya conformando la textura general. El panel modular facilita la instalaci\u00f3n y<span class=\"Apple-converted-space\">\u00a0 <\/span>poder contabilizar cuanta textura 3D hay por metro cuadrado.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-full wp-image-1029\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/ensemblado-de-textura.jpg?resize=640%2C427\" alt=\"Las texturas en 3D est\u00e1n en plena tendencia en el dise\u00f1o de espacios interiores, pues es un soluci\u00f3n pr\u00e1ctica e innovadora que genera m\u00faltiples posibilidades para un ambiente, combinan f\u00e1cilmente con el mobiliario y generan much\u00edsima personalidad al espacio. Con esta peque\u00f1a introducci\u00f3n, presentamos lo que desarrollamos para el espacio interior del Zeviche, un restaurante especializado en todo tipo de ceviches, como su nombre lo indica. Las texturas 3D generan mucha atenci\u00f3n y m\u00faltiples efectos, primero por sus diferentes lecturas de perspectiva y luego, al generar una trama de impacto visual, que hace que las paredes no requieran de ning\u00fan otro tipo de decoraci\u00f3n, como cuadros, espejos o estanter\u00edas. El Zeviche requer\u00eda de una textura que semeje las escamas de un pez, la materia prima de la mayor\u00eda de sus platos. Es as\u00ed que la esencia de la textura fue una placa con la forma de una escama con la que se desarroll\u00f3 todo un panel mas grande. En cada panel, cada placa est\u00e1 instalada con una inclinaci\u00f3n para dar la profundidad requerida y que se vaya conformando la textura general. El panel modular facilita la instalaci\u00f3n y poder contabilizar cuanta textura 3D hay por metro cuadrado. Este producto, ya se encuentra desarrollado y esquematizado para poder ser instalado en cualquier pared. Los colores y su paleta se pueden cambiar muy f\u00e1cilmente dependiendo de la personalidad que se le quiera dar al ambiente. As\u00ed mismo estamos en etapa de experimentaci\u00f3n para su ubicaci\u00f3n en diferentes tipos de mobiliario. Desde cajones de escritorios, hasta muebles de cocina. As\u00ed que cuando pienses en darle mas vida a un espacio o a tus objetos, piensa en crear una textura 3D. Tenemos otra experiencia de textura 3D en el espacio del restaurante el Zanto, que se puede ver en nuestra secci\u00f3n de portafolio.\" width=\"640\" height=\"427\" srcset=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/ensemblado-de-textura.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/ensemblado-de-textura.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/ensemblado-de-textura.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/ensemblado-de-textura.jpg?resize=1024%2C683&amp;ssl=1 1024w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Este producto, ya se encuentra desarrollado y esquematizado para poder ser instalado en cualquier pared. Los colores y su paleta se pueden cambiar muy f\u00e1cilmente dependiendo de la personalidad que se le quiera dar al ambiente. As\u00ed mismo estamos en etapa de experimentaci\u00f3n para su ubicaci\u00f3n en diferentes tipos de mobiliario. Desde cajones de escritorios, hasta muebles de cocina. As\u00ed que cuando pienses en darle mas vida a un espacio o a tus objetos, piensa en crear una textura 3D. Tenemos otra experiencia de textura 3D en el espacio del restaurante el Zanto, que se puede ver en nuestra secci\u00f3n de portafolio.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las texturas en 3D est\u00e1n en plena tendencia en el dise\u00f1o de espacios interiores, pues es un soluci\u00f3n pr\u00e1ctica e innovadora que genera m\u00faltiples posibilidades para un ambiente, combinan f\u00e1cilmente con el mobiliario y generan much\u00edsima personalidad al espacio. Con esta peque\u00f1a introducci\u00f3n, presentamos lo que desarrollamos para el espacio interior del Zeviche, un restaurante [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"_joinchat":[],"footnotes":""},"categories":[61],"tags":[],"class_list":["post-1023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips-de-diseno"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>que es una textura 3D para paredes en el dise\u00f1o de un espacio interior<\/title>\n<meta name=\"description\" content=\"Textura 3D en el caso del espacio interior del restaurante el Zeviche. Placas que recrean las escamas de pez, que generan una textura en las paredes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"que es una textura 3D para paredes en el dise\u00f1o de un espacio interior\" \/>\n<meta property=\"og:description\" content=\"Textura 3D en el caso del espacio interior del restaurante el Zeviche. Placas que recrean las escamas de pez, que generan una textura en las paredes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"Ficto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fictoec\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-05T20:03:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-10T16:19:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/textura-zeviche.jpg?fit=1280%2C854&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucho Vallejo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fictoec\" \/>\n<meta name=\"twitter:site\" content=\"@fictoec\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucho Vallejo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/\"},\"author\":{\"name\":\"Lucho Vallejo\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#\\\/schema\\\/person\\\/e12222e421b68802037c69c64a7aa578\"},\"headline\":\"Que es una textura 3D\",\"datePublished\":\"2019-06-05T20:03:41+00:00\",\"dateModified\":\"2019-06-10T16:19:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/\"},\"wordCount\":339,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/textura-zeviche.jpg?fit=1280%2C854&ssl=1\",\"articleSection\":[\"Tips de Dise\u00f1o\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/\",\"url\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/\",\"name\":\"que es una textura 3D para paredes en el dise\u00f1o de un espacio interior\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/textura-zeviche.jpg?fit=1280%2C854&ssl=1\",\"datePublished\":\"2019-06-05T20:03:41+00:00\",\"dateModified\":\"2019-06-10T16:19:05+00:00\",\"description\":\"Textura 3D en el caso del espacio interior del restaurante el Zeviche. Placas que recrean las escamas de pez, que generan una textura en las paredes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/textura-zeviche.jpg?fit=1280%2C854&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/textura-zeviche.jpg?fit=1280%2C854&ssl=1\",\"width\":1280,\"height\":854,\"caption\":\"Las texturas en 3D est\u00e1n en plena tendencia en el dise\u00f1o de espacios interiores, pues es un soluci\u00f3n pr\u00e1ctica e innovadora que genera m\u00faltiples posibilidades para un ambiente, combinan f\u00e1cilmente con el mobiliario y generan much\u00edsima personalidad al espacio. Con esta peque\u00f1a introducci\u00f3n, presentamos lo que desarrollamos para el espacio interior del Zeviche, un restaurante especializado en todo tipo de ceviches, como su nombre lo indica. Las texturas 3D generan mucha atenci\u00f3n y m\u00faltiples efectos, primero por sus diferentes lecturas de perspectiva y luego, al generar una trama de impacto visual, que hace que las paredes no requieran de ning\u00fan otro tipo de decoraci\u00f3n, como cuadros, espejos o estanter\u00edas. El Zeviche requer\u00eda de una textura que semeje las escamas de un pez, la materia prima de la mayor\u00eda de sus platos. Es as\u00ed que la esencia de la textura fue una placa con la forma de una escama con la que se desarroll\u00f3 todo un panel mas grande. En cada panel, cada placa est\u00e1 instalada con una inclinaci\u00f3n para dar la profundidad requerida y que se vaya conformando la textura general. El panel modular facilita la instalaci\u00f3n y poder contabilizar cuanta textura 3D hay por metro cuadrado. Este producto, ya se encuentra desarrollado y esquematizado para poder ser instalado en cualquier pared. Los colores y su paleta se pueden cambiar muy f\u00e1cilmente dependiendo de la personalidad que se le quiera dar al ambiente. As\u00ed mismo estamos en etapa de experimentaci\u00f3n para su ubicaci\u00f3n en diferentes tipos de mobiliario. Desde cajones de escritorios, hasta muebles de cocina. As\u00ed que cuando pienses en darle mas vida a un espacio o a tus objetos, piensa en crear una textura 3D. Tenemos otra experiencia de textura 3D en el espacio del restaurante el Zanto, que se puede ver en nuestra secci\u00f3n de portafolio.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/que-es-una-textura-3d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Que es una textura 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#website\",\"url\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/\",\"name\":\"Ficto. Dise\u00f1o Industrial Ecuador\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#organization\",\"name\":\"Ficto\",\"url\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/ficto_logo_pagina.png?fit=263%2C300\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/ficto_logo_pagina.png?fit=263%2C300\",\"width\":263,\"height\":300,\"caption\":\"Ficto\"},\"image\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fictoec\\\/\",\"https:\\\/\\\/x.com\\\/fictoec\",\"https:\\\/\\\/www.instagram.com\\\/fictoec\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#\\\/schema\\\/person\\\/e12222e421b68802037c69c64a7aa578\",\"name\":\"Lucho Vallejo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed0aa8917c571be02a3c0c68097693f6b775cec49c01f21793571561dce0b6e1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed0aa8917c571be02a3c0c68097693f6b775cec49c01f21793571561dce0b6e1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed0aa8917c571be02a3c0c68097693f6b775cec49c01f21793571561dce0b6e1?s=96&d=mm&r=g\",\"caption\":\"Lucho Vallejo\"},\"url\":\"https:\\\/\\\/ficto.com.ec\\\/ficto\\\/author\\\/lucho\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"que es una textura 3D para paredes en el dise\u00f1o de un espacio interior","description":"Textura 3D en el caso del espacio interior del restaurante el Zeviche. Placas que recrean las escamas de pez, que generan una textura en las paredes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/","og_locale":"en_US","og_type":"article","og_title":"que es una textura 3D para paredes en el dise\u00f1o de un espacio interior","og_description":"Textura 3D en el caso del espacio interior del restaurante el Zeviche. Placas que recrean las escamas de pez, que generan una textura en las paredes.","og_url":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/","og_site_name":"Ficto","article_publisher":"https:\/\/www.facebook.com\/fictoec\/","article_published_time":"2019-06-05T20:03:41+00:00","article_modified_time":"2019-06-10T16:19:05+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/textura-zeviche.jpg?fit=1280%2C854&ssl=1","type":"image\/jpeg"}],"author":"Lucho Vallejo","twitter_card":"summary_large_image","twitter_creator":"@fictoec","twitter_site":"@fictoec","twitter_misc":{"Written by":"Lucho Vallejo","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/#article","isPartOf":{"@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/"},"author":{"name":"Lucho Vallejo","@id":"http:\/\/ficto.com.ec\/ficto\/#\/schema\/person\/e12222e421b68802037c69c64a7aa578"},"headline":"Que es una textura 3D","datePublished":"2019-06-05T20:03:41+00:00","dateModified":"2019-06-10T16:19:05+00:00","mainEntityOfPage":{"@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/"},"wordCount":339,"commentCount":0,"publisher":{"@id":"http:\/\/ficto.com.ec\/ficto\/#organization"},"image":{"@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/textura-zeviche.jpg?fit=1280%2C854&ssl=1","articleSection":["Tips de Dise\u00f1o"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/","url":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/","name":"que es una textura 3D para paredes en el dise\u00f1o de un espacio interior","isPartOf":{"@id":"http:\/\/ficto.com.ec\/ficto\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/#primaryimage"},"image":{"@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/textura-zeviche.jpg?fit=1280%2C854&ssl=1","datePublished":"2019-06-05T20:03:41+00:00","dateModified":"2019-06-10T16:19:05+00:00","description":"Textura 3D en el caso del espacio interior del restaurante el Zeviche. Placas que recrean las escamas de pez, que generan una textura en las paredes.","breadcrumb":{"@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/#primaryimage","url":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/textura-zeviche.jpg?fit=1280%2C854&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/textura-zeviche.jpg?fit=1280%2C854&ssl=1","width":1280,"height":854,"caption":"Las texturas en 3D est\u00e1n en plena tendencia en el dise\u00f1o de espacios interiores, pues es un soluci\u00f3n pr\u00e1ctica e innovadora que genera m\u00faltiples posibilidades para un ambiente, combinan f\u00e1cilmente con el mobiliario y generan much\u00edsima personalidad al espacio. Con esta peque\u00f1a introducci\u00f3n, presentamos lo que desarrollamos para el espacio interior del Zeviche, un restaurante especializado en todo tipo de ceviches, como su nombre lo indica. Las texturas 3D generan mucha atenci\u00f3n y m\u00faltiples efectos, primero por sus diferentes lecturas de perspectiva y luego, al generar una trama de impacto visual, que hace que las paredes no requieran de ning\u00fan otro tipo de decoraci\u00f3n, como cuadros, espejos o estanter\u00edas. El Zeviche requer\u00eda de una textura que semeje las escamas de un pez, la materia prima de la mayor\u00eda de sus platos. Es as\u00ed que la esencia de la textura fue una placa con la forma de una escama con la que se desarroll\u00f3 todo un panel mas grande. En cada panel, cada placa est\u00e1 instalada con una inclinaci\u00f3n para dar la profundidad requerida y que se vaya conformando la textura general. El panel modular facilita la instalaci\u00f3n y poder contabilizar cuanta textura 3D hay por metro cuadrado. Este producto, ya se encuentra desarrollado y esquematizado para poder ser instalado en cualquier pared. Los colores y su paleta se pueden cambiar muy f\u00e1cilmente dependiendo de la personalidad que se le quiera dar al ambiente. As\u00ed mismo estamos en etapa de experimentaci\u00f3n para su ubicaci\u00f3n en diferentes tipos de mobiliario. Desde cajones de escritorios, hasta muebles de cocina. As\u00ed que cuando pienses en darle mas vida a un espacio o a tus objetos, piensa en crear una textura 3D. Tenemos otra experiencia de textura 3D en el espacio del restaurante el Zanto, que se puede ver en nuestra secci\u00f3n de portafolio."},{"@type":"BreadcrumbList","@id":"https:\/\/ficto.com.ec\/ficto\/que-es-una-textura-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/ficto.com.ec\/ficto\/"},{"@type":"ListItem","position":2,"name":"Que es una textura 3D"}]},{"@type":"WebSite","@id":"http:\/\/ficto.com.ec\/ficto\/#website","url":"http:\/\/ficto.com.ec\/ficto\/","name":"Ficto. Dise\u00f1o Industrial Ecuador","description":"","publisher":{"@id":"http:\/\/ficto.com.ec\/ficto\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/ficto.com.ec\/ficto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/ficto.com.ec\/ficto\/#organization","name":"Ficto","url":"http:\/\/ficto.com.ec\/ficto\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/ficto.com.ec\/ficto\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/02\/ficto_logo_pagina.png?fit=263%2C300","contentUrl":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/02\/ficto_logo_pagina.png?fit=263%2C300","width":263,"height":300,"caption":"Ficto"},"image":{"@id":"http:\/\/ficto.com.ec\/ficto\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fictoec\/","https:\/\/x.com\/fictoec","https:\/\/www.instagram.com\/fictoec"]},{"@type":"Person","@id":"http:\/\/ficto.com.ec\/ficto\/#\/schema\/person\/e12222e421b68802037c69c64a7aa578","name":"Lucho Vallejo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ed0aa8917c571be02a3c0c68097693f6b775cec49c01f21793571561dce0b6e1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed0aa8917c571be02a3c0c68097693f6b775cec49c01f21793571561dce0b6e1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed0aa8917c571be02a3c0c68097693f6b775cec49c01f21793571561dce0b6e1?s=96&d=mm&r=g","caption":"Lucho Vallejo"},"url":"https:\/\/ficto.com.ec\/ficto\/author\/lucho\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/06\/textura-zeviche.jpg?fit=1280%2C854&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/posts\/1023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/comments?post=1023"}],"version-history":[{"count":5,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/posts\/1023\/revisions"}],"predecessor-version":[{"id":1046,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/posts\/1023\/revisions\/1046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/media\/1032"}],"wp:attachment":[{"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/media?parent=1023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/categories?post=1023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/tags?post=1023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}