{"id":9668,"date":"2025-01-05T22:08:44","date_gmt":"2025-01-05T22:08:44","guid":{"rendered":"http:\/\/ficto.com.ec\/ficto\/?post_type=portfolio&#038;p=9668"},"modified":"2025-04-14T17:19:00","modified_gmt":"2025-04-14T17:19:00","slug":"diseno-restaurante-sur-parrilla","status":"publish","type":"portfolio","link":"https:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/","title":{"rendered":"Sur Parrilla"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9668\" class=\"elementor elementor-9668\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5fc528a wrapper-smaller elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fc528a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4898046\" data-id=\"4898046\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-212ba0f wrapper-smaller elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"212ba0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a84e10e\" data-id=\"a84e10e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb2f8a8 elementor-widget elementor-widget-aliothtextwrapper\" data-id=\"fb2f8a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothtextwrapper.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<div class=\"text-wrapper align-left\">\n\n    <h3 class=\"has-anim\" data-animation=\"linesUp\" data-duration=\"1.5\" data-delay=\"0.1\" data-stagger=\"0.1\">\n\n<h2>La Birrer\u00eda: Donde la M\u00fasica y la Gastronom\u00eda se Fusionan<\/h2>\n\n<h4>En el coraz\u00f3n del parque de Cumbay\u00e1, en una encantadora galer\u00eda comercial con aires de hacienda, se encuentra La Birrer\u00eda. Este restaurante, que ha dejado huella en la escena gastron\u00f3mica de Quito, no es solo un lugar para comer, es una experiencia que combina una oferta culinaria excepcional con la energ\u00eda vibrante del rock en vivo. Con el paso de los a\u00f1os, La Birrer\u00eda se ha convertido en un punto de referencia, tanto por sus hamburguesas irresistibles como por la atm\u00f3sfera que se respira los jueves y viernes cuando la banda de rock enciende la noche.<\/h4><\/h3>\n<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bdcdaa elementor-widget elementor-widget-aliothtextwrapper\" data-id=\"0bdcdaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothtextwrapper.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<div class=\"text-wrapper align-left\">\n\n    <h4 class=\"has-anim\" data-animation=\"linesUp\" data-duration=\"1.5\" data-delay=\"0.1\" data-stagger=\"0.1\">Worldlets dream of the mind's eye the ash of stellar alchemy descended from astronomers as a patch of light courage of our questions. Vanquish the impossible not a sunrise but a galaxyrise the only home we've ever known vanquish the impossible encyclopaedia galactica concept of the number one? Trillion vanquish the impossible muse about ship of the imagination ship of the imagination kindling the energy hidden in matter.<\/h4>\n<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f743d6e\" data-id=\"f743d6e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7caf763 wrapper-wide elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7caf763\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9e3947\" data-id=\"e9e3947\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a954f1e elementor-widget elementor-widget-aliothsingleimage\" data-id=\"a954f1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothsingleimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Single Image-->\n<div  class=\"single-image center\">\n\n    \n    <img data-recalc-dims=\"1\" decoding=\"async\" class=\"has-anim\" data-animation=\"blockUp\" data-duration=\"1.5\" data-delay=\"0\" data-color=\"#000000\" alt=\"Restaurante Sur, Sur Parrilla, diseno restaurante Sur, diseno restaurantes ecuador, restaurante Quito, dise\u00f1o restaurante guayaquil\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2025\/01\/SUR_RDB_03.jpg?w=640\">\n\n    \n<\/div>\n<!--\/Single Image-->\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9c8986e\" data-id=\"9c8986e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e17b3ed elementor-widget elementor-widget-aliothsingleimage\" data-id=\"e17b3ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothsingleimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Single Image-->\n<div  class=\"single-image center\">\n\n    \n    <img data-recalc-dims=\"1\" decoding=\"async\" class=\"has-anim\" data-animation=\"blockUp\" data-duration=\"1.5\" data-delay=\"0\" data-color=\"#000000\" alt=\"Restaurante Sur, Sur Parrilla, diseno restaurante Sur, diseno restaurantes ecuador, restaurante Quito, dise\u00f1o restaurante guayaquil\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2025\/01\/SUR_RDB_04.jpg?w=640\">\n\n    \n<\/div>\n<!--\/Single Image-->\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-596fe49 wrapper-fuller elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"596fe49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5f3573\" data-id=\"e5f3573\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f944e0 elementor-widget elementor-widget-aliothsingleimage\" data-id=\"5f944e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothsingleimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Single Image-->\n<div  class=\"single-image center\">\n\n    \n    <img data-recalc-dims=\"1\" decoding=\"async\"  alt=\"Restaurante Sur, Sur Parrilla, diseno restaurante Sur, diseno restaurantes ecuador, restaurante Quito\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2025\/01\/SUR_RDB_10.jpg?w=640\">\n\n    \n<\/div>\n<!--\/Single Image-->\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbf58e2 wrapper-wide elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbf58e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eb3743f\" data-id=\"eb3743f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a3f1f89\" data-id=\"a3f1f89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5ed7b1 elementor-widget elementor-widget-aliothtextwrapper\" data-id=\"d5ed7b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothtextwrapper.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<div class=\"text-wrapper align-left\">\n\n    <p class=\"has-anim\" data-animation=\"linesUp\" data-duration=\"1.5\" data-delay=\"0.1\" data-stagger=\"0.02\"><h2>Ficto: Dise\u00f1o de restaurantes con alma<\/h2>\n\n<p>\nEn Ficto, entendemos que el dise\u00f1o de un restaurante no es solo cuesti\u00f3n de est\u00e9tica, sino de crear espacios que cuenten una historia y que generen emociones. El restaurante \"Sur Parrilla Gourmet\" es un ejemplo claro de c\u00f3mo el dise\u00f1o tiene que acompa\u00f1ar la experiencia gastron\u00f3mica. 15 a\u00f1os despu\u00e9s de su apertura intervenimos en el dise\u00f1o de este restaurante para traerlo a la actualidad, sin perder su esencia y trayectoria. <\/br>\nNuestra experiencia en el dise\u00f1o de restaurantes en Ecuador, nos permiti\u00f3 mejorar una atm\u00f3sfera gastron\u00f3mica reconocida en la ciudad de Quito.\n<\/p><\/p>\n<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-499da39 wrapper-wide elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"499da39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24c843c\" data-id=\"24c843c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c547701 elementor-widget elementor-widget-aliothsingleimage\" data-id=\"c547701\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothsingleimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Single Image-->\n<div  class=\"single-image center\">\n\n    \n    <img data-recalc-dims=\"1\" decoding=\"async\" class=\"has-anim\" data-animation=\"slideUp\" data-duration=\"1.5\" data-delay=\"0\" data-color=\"\" alt=\"Restaurante Sur, Sur Parrilla, diseno restaurante Sur, diseno restaurantes ecuador, restaurante Quito, dise\u00f1o restaurante guayaquil\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2025\/01\/SUR_RDB_09.jpg?w=640\">\n\n    \n<\/div>\n<!--\/Single Image-->\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad29855 elementor-widget elementor-widget-aliothsingleimage\" data-id=\"ad29855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothsingleimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Single Image-->\n<div  class=\"single-image center\">\n\n    \n    <img data-recalc-dims=\"1\" decoding=\"async\" class=\"has-anim\" data-animation=\"slideUp\" data-duration=\"1.5\" data-delay=\"0\" data-color=\"\" alt=\"Restaurante Sur, Sur Parrilla, diseno restaurante Sur, diseno restaurantes ecuador, restaurante Quito, dise\u00f1o restaurante guayaquil\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2025\/01\/SUR_RDB_05.jpg?w=640\">\n\n    \n<\/div>\n<!--\/Single Image-->\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba828ed wrapper-wide elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba828ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee29609\" data-id=\"ee29609\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c05976a wrapper-wide elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c05976a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-87dfcd1\" data-id=\"87dfcd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ed2e3f elementor-widget elementor-widget-aliothsingleimage\" data-id=\"5ed2e3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothsingleimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Single Image-->\n<div  class=\"single-image center\">\n\n    \n    <img data-recalc-dims=\"1\" decoding=\"async\" class=\"has-anim\" data-animation=\"blockLeft\" data-duration=\"1\" data-delay=\"0\" data-color=\"#CCC7C2\" alt=\"Restaurante Sur, diseno restaurantes ecuador, restaurante Quito, dise\u00f1o restaurante guayaquil\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2025\/01\/SUR_RDB_13.jpg?w=640\">\n\n    \n<\/div>\n<!--\/Single Image-->\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-86d1aa8 wrapper-wide elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86d1aa8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-28705bf\" data-id=\"28705bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd6d84b elementor-widget elementor-widget-aliothsingleimage\" data-id=\"dd6d84b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothsingleimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Single Image-->\n<div  class=\"single-image center\">\n\n    \n    <img data-recalc-dims=\"1\" decoding=\"async\" class=\"has-anim\" data-animation=\"blockLeft\" data-duration=\"1\" data-delay=\"0\" data-color=\"#CCC7C2\" alt=\"Restaurante Sur, diseno restaurantes ecuador, restaurante Quito, dise\u00f1o restaurante guayaquil\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2025\/01\/SUR_RDB_12.jpg?w=640\">\n\n    \n<\/div>\n<!--\/Single Image-->\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bf66ebf\" data-id=\"bf66ebf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0873d2b elementor-widget elementor-widget-aliothsingleimage\" data-id=\"0873d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothsingleimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Single Image-->\n<div  class=\"single-image center\">\n\n    \n    <img data-recalc-dims=\"1\" decoding=\"async\" class=\"has-anim\" data-animation=\"blockLeft\" data-duration=\"1\" data-delay=\"0\" data-color=\"#CCC7C2\" alt=\"Restaurante Sur, diseno restaurantes ecuador, restaurante Quito, dise\u00f1o restaurante guayaquil\" src=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2025\/01\/SUR_RDB_11.jpg?w=640\">\n\n    \n<\/div>\n<!--\/Single Image-->\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da085c3 wrapper-smaller elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da085c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f3fcde3\" data-id=\"f3fcde3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-f6fcb1f\" data-id=\"f6fcb1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc70b74 elementor-widget elementor-widget-aliothtextwrapper\" data-id=\"dc70b74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothtextwrapper.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<div class=\"text-wrapper align-left\">\n\n    <h5 >Si quieres reservar una mesa en este espacio, la p\u00e1gina de La Birrer\u00eda es: <\/h5>\n<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e53b88d elementor-widget__width-initial elementor-widget elementor-widget-aliothbutton\" data-id=\"e53b88d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothbutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Button-->\n<div class=\"alioth-button align-left button-classic dark\">\n\n    <div class=\"a-button style_1 light\">\n\n        <!--Button URL-->\n        <a href=\"https:\/\/labirreria.com.ec\/\">Website: \"La Birrer\u00eda\"\n            <!--Button Icon-->\n            <i aria-hidden=\"true\" class=\"fas fa-bacon\"><\/i>            <!--\/Button Icon-->\n\n        <\/a>\n        <!--\/Button URL-->\n\n    <\/div>\n\n<\/div>\n    <!--\/Button-->\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e1108e elementor-widget elementor-widget-aliothtextwrapper\" data-id=\"2e1108e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothtextwrapper.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<div class=\"text-wrapper align-left\">\n\n    <h5 >Otro proyecto con el que trabajamos con Z Restaurants es el Zant\u00edsimo en el centro comercial Scala de Cumbay\u00e1 y  lo pueden ver por ac\u00e1:\n<\/h5>\n<\/div>\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1eb75e elementor-widget__width-initial elementor-widget elementor-widget-aliothbutton\" data-id=\"a1eb75e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aliothbutton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!--Button-->\n<div class=\"alioth-button align-left button-classic dark\">\n\n    <div class=\"a-button style_1 light\">\n\n        <!--Button URL-->\n        <a href=\"http:\/\/ficto.com.ec\/ficto\/portfolio\/zantizimo\/\">Dise\u00f1o de restaurantes: Zant\u00edsimo\n            <!--Button Icon-->\n            <i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>            <!--\/Button Icon-->\n\n        <\/a>\n        <!--\/Button URL-->\n\n    <\/div>\n\n<\/div>\n    <!--\/Button-->\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":4848,"template":"","meta":{"_acf_changed":false,"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"project-categories":[105],"class_list":["post-9668","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","project-categories-diseno-de-restaurantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sur Parrilla - Ficto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sur Parrilla - Ficto\" \/>\n<meta property=\"og:description\" content=\"La Birrer\u00eda: Donde la M\u00fasica y la Gastronom\u00eda se Fusionan En el coraz\u00f3n del parque de Cumbay\u00e1, en una encantadora galer\u00eda comercial con aires de hacienda, se encuentra La Birrer\u00eda. Este restaurante, que ha dejado huella en la escena gastron\u00f3mica de Quito, no es solo un lugar para comer, es una experiencia que combina una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/\" \/>\n<meta property=\"og:site_name\" content=\"Ficto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fictoec\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T17:19:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2022\/09\/SUR_RDB_01.jpg?fit=1800%2C1170\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1170\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fictoec\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/portfolio\\\/diseno-restaurante-sur-parrilla\\\/\",\"url\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/portfolio\\\/diseno-restaurante-sur-parrilla\\\/\",\"name\":\"Sur Parrilla - Ficto\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/portfolio\\\/diseno-restaurante-sur-parrilla\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/portfolio\\\/diseno-restaurante-sur-parrilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/SUR_RDB_01.jpg?fit=1800%2C1170&ssl=1\",\"datePublished\":\"2025-01-05T22:08:44+00:00\",\"dateModified\":\"2025-04-14T17:19:00+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/portfolio\\\/diseno-restaurante-sur-parrilla\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/portfolio\\\/diseno-restaurante-sur-parrilla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/portfolio\\\/diseno-restaurante-sur-parrilla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/SUR_RDB_01.jpg?fit=1800%2C1170&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/SUR_RDB_01.jpg?fit=1800%2C1170&ssl=1\",\"width\":1800,\"height\":1170,\"caption\":\"dise\u00f1o de restaurantes ecuador, Paul Astudillo, Lucho Vallejo, food design ecuador, dise\u00f1o bares, diseno interiores quito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/portfolio\\\/diseno-restaurante-sur-parrilla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sur Parrilla\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#website\",\"url\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/\",\"name\":\"Ficto. Dise\u00f1o Industrial Ecuador\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#organization\",\"name\":\"Ficto\",\"url\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/ficto_logo_pagina.png?fit=263%2C300\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/ficto.com.ec\\\/ficto\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/ficto_logo_pagina.png?fit=263%2C300\",\"width\":263,\"height\":300,\"caption\":\"Ficto\"},\"image\":{\"@id\":\"http:\\\/\\\/ficto.com.ec\\\/ficto\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fictoec\\\/\",\"https:\\\/\\\/x.com\\\/fictoec\",\"https:\\\/\\\/www.instagram.com\\\/fictoec\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sur Parrilla - Ficto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/","og_locale":"en_US","og_type":"article","og_title":"Sur Parrilla - Ficto","og_description":"La Birrer\u00eda: Donde la M\u00fasica y la Gastronom\u00eda se Fusionan En el coraz\u00f3n del parque de Cumbay\u00e1, en una encantadora galer\u00eda comercial con aires de hacienda, se encuentra La Birrer\u00eda. Este restaurante, que ha dejado huella en la escena gastron\u00f3mica de Quito, no es solo un lugar para comer, es una experiencia que combina una [&hellip;]","og_url":"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/","og_site_name":"Ficto","article_publisher":"https:\/\/www.facebook.com\/fictoec\/","article_modified_time":"2025-04-14T17:19:00+00:00","og_image":[{"width":1800,"height":1170,"url":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2022\/09\/SUR_RDB_01.jpg?fit=1800%2C1170","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@fictoec","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/","url":"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/","name":"Sur Parrilla - Ficto","isPartOf":{"@id":"http:\/\/ficto.com.ec\/ficto\/#website"},"primaryImageOfPage":{"@id":"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/#primaryimage"},"image":{"@id":"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2022\/09\/SUR_RDB_01.jpg?fit=1800%2C1170&ssl=1","datePublished":"2025-01-05T22:08:44+00:00","dateModified":"2025-04-14T17:19:00+00:00","breadcrumb":{"@id":"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/#primaryimage","url":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2022\/09\/SUR_RDB_01.jpg?fit=1800%2C1170&ssl=1","contentUrl":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2022\/09\/SUR_RDB_01.jpg?fit=1800%2C1170&ssl=1","width":1800,"height":1170,"caption":"dise\u00f1o de restaurantes ecuador, Paul Astudillo, Lucho Vallejo, food design ecuador, dise\u00f1o bares, diseno interiores quito"},{"@type":"BreadcrumbList","@id":"http:\/\/ficto.com.ec\/ficto\/portfolio\/diseno-restaurante-sur-parrilla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/ficto.com.ec\/ficto\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"http:\/\/ficto.com.ec\/ficto\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Sur Parrilla"}]},{"@type":"WebSite","@id":"http:\/\/ficto.com.ec\/ficto\/#website","url":"http:\/\/ficto.com.ec\/ficto\/","name":"Ficto. Dise\u00f1o Industrial Ecuador","description":"","publisher":{"@id":"http:\/\/ficto.com.ec\/ficto\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/ficto.com.ec\/ficto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/ficto.com.ec\/ficto\/#organization","name":"Ficto","url":"http:\/\/ficto.com.ec\/ficto\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/ficto.com.ec\/ficto\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/02\/ficto_logo_pagina.png?fit=263%2C300","contentUrl":"https:\/\/i0.wp.com\/ficto.com.ec\/ficto\/wp-content\/uploads\/2019\/02\/ficto_logo_pagina.png?fit=263%2C300","width":263,"height":300,"caption":"Ficto"},"image":{"@id":"http:\/\/ficto.com.ec\/ficto\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fictoec\/","https:\/\/x.com\/fictoec","https:\/\/www.instagram.com\/fictoec"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/portfolio\/9668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":5,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/portfolio\/9668\/revisions"}],"predecessor-version":[{"id":11029,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/portfolio\/9668\/revisions\/11029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/media\/4848"}],"wp:attachment":[{"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/media?parent=9668"}],"wp:term":[{"taxonomy":"project-categories","embeddable":true,"href":"https:\/\/ficto.com.ec\/ficto\/wp-json\/wp\/v2\/project-categories?post=9668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}